{"id":2600,"date":"2016-05-04T14:03:28","date_gmt":"2016-05-04T14:03:28","guid":{"rendered":"http:\/\/ayro.select-themes.com\/?page_id=2600"},"modified":"2016-05-04T14:03:28","modified_gmt":"2016-05-04T14:03:28","slug":"portfolio-home","status":"publish","type":"page","link":"https:\/\/nextiait.com\/index.php\/portfolio-home\/","title":{"rendered":"Portfolio Home"},"content":{"rendered":"<p>[vc_row content_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1463558643629{padding-top: 95px !important;padding-bottom: 100px !important;}&#8221;][vc_column]\n<div class=\"qodef-custom-font-holder\" style=\"font-family: Catamaran;font-size: 60px;line-height: 65px;font-weight: 700;letter-spacing: -1px;text-align: center;color: #282d33\" data-font-size= 60 data-line-height= 65>\n\tWelcome<\/div>[vc_empty_space height=&#8221;13px&#8221;][vc_column_text]<\/p>\n<h4>Create the Perfect Home for All Your Awesome Projects<\/h4>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row content_width=&#8221;grid&#8221; css=&#8221;.vc_custom_1463558680158{padding-bottom: 90px !important;}&#8221;][vc_column]<div class = \"qodef-portfolio-list-holder-outer qodef-ptf-gallery-circle qodef-ptf-four-columns\" data-next-page= 2 data-type= gallery-circle data-columns= four data-grid-size= three data-order-by= menu_order data-order= ASC data-number= -1 data-image-size= full data-filter= no data-filter-order-by= name data-category= creative data-show-load-more= no data-title-tag= h5 data-max-num-pages = 0><div class = \"qodef-portfolio-list-holder clearfix\" ><article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/beer-minimal-packaging-design-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-1.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-1-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-1-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-1-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-1-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tBeer Minimal Packaging Design\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/clean-brand-identity-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-14.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-14.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-14-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-14-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-14-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-14-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tClean Brand Identity\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/coffee-brand-digital-branding-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-3.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-3-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-3-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-3-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-3-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tCoffee Brand Digital Branding\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/fabric-bag-brand-design-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-4.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-4-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-4-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-4-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-4-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tFabric Bag Brand Design\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/limited-edition-packaging-design-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tLimited Edition Packaging Design\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/momin-brand-identity-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-6.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-6-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-6-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-6-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-6-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tMomin Brand Identity\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/neon-cafe-visual-identity-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tNeon Cafe Visual Identity\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/paper-landscape-print-design-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-8.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-8.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-8-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-8-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-8-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-8-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tPaper Landscape Print Design\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/patterns-textures-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-9.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-9.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-9-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-9-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-9-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-9-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tPatterns &#038; Textures\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/red-design-issue-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-10.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-10.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-10-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-10-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-10-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-10-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tRed Design Issue\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/wearable-tech-digital-advertising-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-11.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-11.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-11-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-11-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-11-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-11-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tWearable Tech Digital Advertising\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/2015-expo-identity-2\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-12.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-12.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-12-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-12-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-12-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-12-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\t2015 Expo Identity\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/beer-minimal-packaging-design-3\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-13.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-13.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-13-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-13-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-13-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-13-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tBeer Minimal Packaging Design\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/clean-brand-identity-3\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-2.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-2-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-2-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-2-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-2-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tClean Brand Identity\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/coffee-brand-digital-branding-3\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-5-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tCoffee Brand Digital Branding\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<article class=\"qodef-portfolio-item mix portfolio_category_66\" >\r\n\t<a class =\"qodef-portfolio-link\" href=\"https:\/\/nextiait.com\/index.php\/portfolio-item\/fabric-bag-brand-design-3\/\"><\/a>\r\n\t<div class=\"qodef-image-circle-overlay\"><\/div>\r\n\t<div class = \"qodef-item-image-holder\">\r\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"a\" srcset=\"https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7.jpg 600w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-300x300.jpg 300w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-100x100.jpg 100w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-150x150.jpg 150w, https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/circle-portfolio-7-550x550.jpg 550w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t<\/div>\r\n\t<div class=\"qodef-item-text-overlay\">\r\n\t\t<div class=\"qodef-item-text-overlay-inner\">\r\n\t\t\t<div class=\"qodef-item-text-holder\">\r\n\t\t\t\t<h5 class=\"qodef-item-title\">\r\n\t\t\t\t\tFabric Bag Brand Design\t\t\t\t<\/h5>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t<\/div>\r\n<\/article>\r\n<div class='qodef-filler'><\/div>\n<div class='qodef-filler'><\/div>\n<div class='qodef-filler'><\/div>\n<div class='qodef-filler'><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]\t<div class=\"qodef-call-to-action normal\" style=\"background-image: url(https:\/\/nextiait.com\/wp-content\/uploads\/2016\/05\/call-to-action-image.jpg)\">\n\n\t\t\t\t<div class=\"qodef-container-inner\">\n\t\t\t\t\t<div class=\"qodef-call-to-action-row-75-25 clearfix\" style=\"padding: 70px 0px;\">\n\t\t\t\t\t\t<div class=\"qodef-text-wrapper qodef-call-to-action-column1 qodef-call-to-action-cell\">\n\t\t\t\t\t\t\t\t\t<div class=\"qodef-call-to-action-text\" >\n<h3><span style=\"color: #ffffff;\">Like what you see? Let&#8217;s collaborate!<\/span><\/h3>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"qodef-button-wrapper qodef-call-to-action-column2 qodef-call-to-action-cell\" style =\"text-align: right ;\">\n\t\t\t\t\t\t<a href=\"#\" target=\"_self\" style=\"color: #ffffff;background-color: rgba(255,255,255,0.01);border-color: rgba(255,255,255,0.5)\" class=\"qodef-btn qodef-btn-medium qodef-btn-solid qodef-btn-custom-hover-bg qodef-btn-custom-border-hover qodef-btn-custom-hover-color qodef-btn-icon\" data-hover-bg-color=\"#ffffff\" data-hover-color=\"#282d33\" data-hover-border-color=\"#ffffff\" >    <span class=\"qodef-btn-text\">contact<\/span>    <span aria-hidden=\"true\" class=\"qodef-icon-font-elegant arrow_carrot-right \" ><\/span><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row content_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1463558643629{padding-top: 95px !important;padding-bottom: 100px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;13px&#8221;][vc_column_text] Create the Perfect Home for All Your Awesome Projects [\/vc_column_text][\/vc_column][\/vc_row][vc_row content_width=&#8221;grid&#8221; css=&#8221;.vc_custom_1463558680158{padding-bottom: 90px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-2600","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/pages\/2600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/comments?post=2600"}],"version-history":[{"count":0,"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/pages\/2600\/revisions"}],"wp:attachment":[{"href":"https:\/\/nextiait.com\/index.php\/wp-json\/wp\/v2\/media?parent=2600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}